{"id":142,"count":2,"description":"","link":"https:\/\/www.megomuseum.com\/galleries\/tag\/bendy\/","name":"Bendy","slug":"bendy","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.megomuseum.com\/galleries\/wp-json\/wp\/v2\/tags\/142","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.megomuseum.com\/galleries\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.megomuseum.com\/galleries\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.megomuseum.com\/galleries\/wp-json\/wp\/v2\/posts?tags=142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}